{"id":71781,"date":"2022-06-09T11:16:36","date_gmt":"2022-06-09T15:16:36","guid":{"rendered":"https:\/\/mayahtt.com\/?p=71781"},"modified":"2022-06-09T11:16:36","modified_gmt":"2022-06-09T15:16:36","slug":"feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie","status":"publish","type":"post","link":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/","title":{"rendered":"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie"},"content":{"rendered":"<p>L\u2019intelligence artificielle (IA) ne rel\u00e8ve plus de la science-fiction. Elle offre des avantages concrets dans les domaines de l\u2019ing\u00e9nierie, de la fabrication et des op\u00e9rations. Elle promet de faire progresser ces industries et de changer notre fa\u00e7on de travailler, de vivre et de cr\u00e9er.<\/p>\n<h2>Comment et o\u00f9 commencer?<\/h2>\n<p>Selon certaines estimations, 85% des projets d\u2019IA se soldent par un \u00e9chec. De nombreuses entreprises \u00e9prouvent des probl\u00e8mes avec leurs donn\u00e9es. Une feuille de route d\u2019IA peutvous aider \u00e0 assurer que vous disposez des bonnes donn\u00e9es (et en quantit\u00e9 suffisante) et d\u2019une strat\u00e9gie qui contribueront \u00e0 votre succ\u00e8s.<\/p>\n<h2>\u00c0 quoi ressemble une feuille de route d\u2019intelligence artificielle? Comment peut-on l\u2019utiliser pour faire progresser une strat\u00e9gie commerciale?<\/h2>\n<p>D\u00e9marrez du bon pied gr\u00e2ce aux conseils de nos experts. Dans notre rapport intitul\u00e9 \u00ab<a href=\"https:\/\/mayahtt.com\/brochures\/WhitePaper%20Call%20of%20AI.pdf\">L\u2019appel de l\u2019IA pour les ing\u00e9nieurs<\/a>\u00bb, nous pr\u00e9sentons les meilleures pratiques de planification et de mise en \u0153uvre, les avantages d\u2019avoir un partenaire comp\u00e9tent en mati\u00e8re d\u2019IA et la meilleure mani\u00e8re de s\u2019engager sur la voie de l\u2019IA.<\/p>\n<p>Il vous permettra de bien comprendre les concepts et les strat\u00e9gies que les entreprises doivent envisager pour passer \u00e0 l\u2019IA, et ce, qu\u2019elles soient petites ou grandes.<\/p>\n<p><a href=\"https:\/\/mayahtt.com\/brochures\/WhitePaper%20Call%20of%20AI.pdf\">T\u00e9l\u00e9chargez ce rapport<\/a> d\u00e8s aujourd\u2019hui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019intelligence artificielle (IA) ne rel\u00e8ve plus de la science-fiction. Elle offre des avantages concrets dans les domaines de l\u2019ing\u00e9nierie, de la fabrication et des op\u00e9rations. Elle promet de faire progresser ces industries et de changer notre fa\u00e7on de travailler, de vivre et de cr\u00e9er. Comment et o\u00f9 commencer? Selon certaines estimations, 85% des projets d\u2019IA [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":71822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[559,303],"tags":[],"class_list":["post-71781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-fr-fr","category-blogue"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie - Maya HTT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie - Maya HTT\" \/>\n<meta property=\"og:description\" content=\"L\u2019intelligence artificielle (IA) ne rel\u00e8ve plus de la science-fiction. Elle offre des avantages concrets dans les domaines de l\u2019ing\u00e9nierie, de la fabrication et des op\u00e9rations. Elle promet de faire progresser ces industries et de changer notre fa\u00e7on de travailler, de vivre et de cr\u00e9er. Comment et o\u00f9 commencer? Selon certaines estimations, 85% des projets d\u2019IA [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/\" \/>\n<meta property=\"og:site_name\" content=\"Maya HTT\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T15:16:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mayahtt.com\/wp-content\/uploads\/2022\/05\/AI_Microchip_Blog_Header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mark-James M\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mark-James M\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/\"},\"author\":{\"name\":\"Mark-James M\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#\\\/schema\\\/person\\\/dd14c9be5c93cb0f73a52a7ae23be736\"},\"headline\":\"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie\",\"datePublished\":\"2022-06-09T15:16:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mayahtt.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AI_Microchip_Blog_Header.jpg\",\"articleSection\":[\"Articles\",\"Blogue\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/\",\"url\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/\",\"name\":\"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie - Maya HTT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mayahtt.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AI_Microchip_Blog_Header.jpg\",\"datePublished\":\"2022-06-09T15:16:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mayahtt.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AI_Microchip_Blog_Header.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mayahtt.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/AI_Microchip_Blog_Header.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"A microchip with AI lettering embossed on it\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/\",\"name\":\"Maya HTT\",\"description\":\"Engineering Software Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#organization\",\"name\":\"Maya HTT\",\"url\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mayahtt.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/mayahtt-thumbnail.png\",\"contentUrl\":\"https:\\\/\\\/mayahtt.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/mayahtt-thumbnail.png\",\"width\":300,\"height\":300,\"caption\":\"Maya HTT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/#\\\/schema\\\/person\\\/dd14c9be5c93cb0f73a52a7ae23be736\",\"name\":\"Mark-James M\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6633256b75e0c71a2b74f5faf2db88788c3e2da7f903c4a12bd7421fbb65cebf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6633256b75e0c71a2b74f5faf2db88788c3e2da7f903c4a12bd7421fbb65cebf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6633256b75e0c71a2b74f5faf2db88788c3e2da7f903c4a12bd7421fbb65cebf?s=96&d=mm&r=g\",\"caption\":\"Mark-James M\"},\"url\":\"https:\\\/\\\/www.mayahtt.com\\\/fr\\\/blog\\\/author\\\/markj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie - Maya HTT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/","og_locale":"fr_FR","og_type":"article","og_title":"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie - Maya HTT","og_description":"L\u2019intelligence artificielle (IA) ne rel\u00e8ve plus de la science-fiction. Elle offre des avantages concrets dans les domaines de l\u2019ing\u00e9nierie, de la fabrication et des op\u00e9rations. Elle promet de faire progresser ces industries et de changer notre fa\u00e7on de travailler, de vivre et de cr\u00e9er. Comment et o\u00f9 commencer? Selon certaines estimations, 85% des projets d\u2019IA [&hellip;]","og_url":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/","og_site_name":"Maya HTT","article_published_time":"2022-06-09T15:16:36+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.mayahtt.com\/wp-content\/uploads\/2022\/05\/AI_Microchip_Blog_Header.jpg","type":"image\/jpeg"}],"author":"Mark-James M","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mark-James M","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/#article","isPartOf":{"@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/"},"author":{"name":"Mark-James M","@id":"https:\/\/www.mayahtt.com\/fr\/#\/schema\/person\/dd14c9be5c93cb0f73a52a7ae23be736"},"headline":"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie","datePublished":"2022-06-09T15:16:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/"},"wordCount":252,"publisher":{"@id":"https:\/\/www.mayahtt.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mayahtt.com\/wp-content\/uploads\/2022\/05\/AI_Microchip_Blog_Header.jpg","articleSection":["Articles","Blogue"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/","url":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/","name":"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie - Maya HTT","isPartOf":{"@id":"https:\/\/www.mayahtt.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/#primaryimage"},"image":{"@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mayahtt.com\/wp-content\/uploads\/2022\/05\/AI_Microchip_Blog_Header.jpg","datePublished":"2022-06-09T15:16:36+00:00","breadcrumb":{"@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/#primaryimage","url":"https:\/\/www.mayahtt.com\/wp-content\/uploads\/2022\/05\/AI_Microchip_Blog_Header.jpg","contentUrl":"https:\/\/www.mayahtt.com\/wp-content\/uploads\/2022\/05\/AI_Microchip_Blog_Header.jpg","width":1920,"height":1080,"caption":"A microchip with AI lettering embossed on it"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mayahtt.com\/fr\/blog\/feuille-de-route-dia-reussite-de-lingenierie-grace-aux-donnees-eta-une-bonne-strategie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mayahtt.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Feuille de route d\u2019IA: r\u00e9ussite de l\u2019ing\u00e9nierie gr\u00e2ce aux donn\u00e9es et\u00e0 une bonne strat\u00e9gie"}]},{"@type":"WebSite","@id":"https:\/\/www.mayahtt.com\/fr\/#website","url":"https:\/\/www.mayahtt.com\/fr\/","name":"Maya HTT","description":"Engineering Software Solutions","publisher":{"@id":"https:\/\/www.mayahtt.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mayahtt.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.mayahtt.com\/fr\/#organization","name":"Maya HTT","url":"https:\/\/www.mayahtt.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mayahtt.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/mayahtt.com\/wp-content\/uploads\/2025\/07\/mayahtt-thumbnail.png","contentUrl":"https:\/\/mayahtt.com\/wp-content\/uploads\/2025\/07\/mayahtt-thumbnail.png","width":300,"height":300,"caption":"Maya HTT"},"image":{"@id":"https:\/\/www.mayahtt.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mayahtt.com\/fr\/#\/schema\/person\/dd14c9be5c93cb0f73a52a7ae23be736","name":"Mark-James M","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6633256b75e0c71a2b74f5faf2db88788c3e2da7f903c4a12bd7421fbb65cebf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6633256b75e0c71a2b74f5faf2db88788c3e2da7f903c4a12bd7421fbb65cebf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6633256b75e0c71a2b74f5faf2db88788c3e2da7f903c4a12bd7421fbb65cebf?s=96&d=mm&r=g","caption":"Mark-James M"},"url":"https:\/\/www.mayahtt.com\/fr\/blog\/author\/markj\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/posts\/71781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/comments?post=71781"}],"version-history":[{"count":0,"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/posts\/71781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/media\/71822"}],"wp:attachment":[{"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/media?parent=71781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/categories?post=71781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mayahtt.com\/fr\/wp-json\/wp\/v2\/tags?post=71781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}